{"id":271,"date":"2016-08-20T11:13:09","date_gmt":"2016-08-20T09:13:09","guid":{"rendered":"http:\/\/www.stammersdorf.at\/stammersdorf-wp\/?p=271"},"modified":"2020-12-15T21:22:05","modified_gmt":"2020-12-15T20:22:05","slug":"anreise","status":"publish","type":"post","link":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/anreise\/","title":{"rendered":"Anreise"},"content":{"rendered":"<h4>Anreise mit&nbsp; \u00f6ffentlichen Verkehrsmitteln:<\/h4>\n<p>Mit der Linie 31 bis zur Endstation Stammersdorf, mit der Linie 125 durch den<br>Ort oder mit der Linie 228 vom Bahnhof Floridsdorf (U 6 und Schnellbahn).&nbsp; Und sollte es bei einem Glaserl Wein einmal sp\u00e4ter geworden sein, gibt es auch eine Nachtbusverbindung bis ins Zentrum.<\/p>\n<p><a href=\"https:\/\/anachb.vor.at\/bin\/query.exe\/dn?L=vs_voranachb\" target=\"_blank\" rel=\"noopener noreferrer\">zur VOR &#8211; Seite<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>Anreise mit dem Auto:<\/h4>\n<p>&#8211; vom Zentrum \u00fcber die Nordbr\u00fccke, Br\u00fcnner Stra\u00dfe bis nach Stammersdorf.<\/p>\n<p>&#8211; vom Westen \u00fcber die A22, bis zur Abfahrt Strebersdorf, \u00fcber die Prager<br>Stra\u00dfe, Ru\u00dfbergstra\u00dfe Richtung Stammersdorf<\/p>\n<p>oder individuell:<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m14!1m12!1m3!1d12625.460848736546!2d16.41816455469184!3d48.29946269122189!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!5e0!3m2!1sde!2sat!4v1573383929454!5m2!1sde!2sat\" width=\"600\" height=\"450\" frameborder=\"0\" style=\"border:0;\" allowfullscreen=\"\"><\/iframe><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>Anreise mit&nbsp; \u00f6ffentlichen Verkehrsmitteln: Mit der Linie 31 bis zur Endstation Stammersdorf, mit der Linie 125 durch denOrt oder mit der Linie 228 vom Bahnhof Floridsdorf (U 6 und Schnellbahn).&nbsp; Und sollte es bei einem Glaserl Wein einmal sp\u00e4ter geworden sein, gibt es auch eine Nachtbusverbindung bis ins Zentrum. zur&hellip;<\/p>\n<p class=\"more-link-wrapper\"><a class=\"more-link\" href=\"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/anreise\/\"><span class=\"fa fa-mail-forward read-more-icon\"><\/span><span class=\"screen-reader-text\">Read More<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-271","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/posts\/271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/comments?post=271"}],"version-history":[{"count":6,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/posts\/271\/revisions"}],"predecessor-version":[{"id":493,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/posts\/271\/revisions\/493"}],"wp:attachment":[{"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/media?parent=271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/categories?post=271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.stammersdorf.at\/stammersdorf-wp\/wp-json\/wp\/v2\/tags?post=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}